{"id":2103,"date":"2024-05-16T16:17:24","date_gmt":"2024-05-16T14:17:24","guid":{"rendered":"https:\/\/avanea.ch\/placements\/"},"modified":"2024-09-03T10:52:27","modified_gmt":"2024-09-03T08:52:27","slug":"placements","status":"publish","type":"page","link":"https:\/\/avanea.ch\/fr\/placements\/","title":{"rendered":"Placements"},"content":{"rendered":"<div class=\"gb-container gb-container-9eb9367f\">\n\n<h2 class=\"wp-block-heading\">Nous adoptons des strat\u00e9gies d&rsquo;investissement \u00e0 long terme afin de garantir la s\u00e9curit\u00e9 de votre \u00e9pargne retraite.<\/h2>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"gb-headline gb-headline-799ce339 gb-headline-text\"><strong>Notre philosophie d&rsquo;investissement<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Apprenez-en plus sur nos pools d&rsquo;investissement, nos principes d&rsquo;investissement ainsi que sur la mani\u00e8re dont votre patrimoine est g\u00e9r\u00e9 de mani\u00e8re responsable.\nNous accordons une grande importance \u00e0 la diversification et \u00e0 la gestion des risques afin de prot\u00e9ger au mieux votre patrimoine tout en profitant des opportunit\u00e9s offertes par les march\u00e9s financiers. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Diversification<\/strong><br>Nous r\u00e9partissons votre capital entre diff\u00e9rentes classes d&rsquo;actifs telles que les actions, les obligations, l&rsquo;immobilier et les placements alternatifs afin de minimiser les risques et de maximiser les opportunit\u00e9s.<\/li>\n\n\n\n<li><strong>Gestion des risques<\/strong><br>Nous attachons une grande importance \u00e0 une gestion \u00e9quilibr\u00e9e des risques.\nGr\u00e2ce \u00e0 une analyse et \u00e0 une gestion cibl\u00e9es des risques, nous prot\u00e9geons votre capital contre les fluctuations importantes du march\u00e9. <\/li>\n\n\n\n<li><strong>Approche \u00e0 long terme<\/strong><br>Nos d\u00e9cisions d&rsquo;investissement sont ax\u00e9es sur le long terme.\nNous adoptons une strat\u00e9gie buy-and-hold afin de profiter des tendances de croissance \u00e0 long terme et de minimiser la volatilit\u00e9 \u00e0 court terme. <\/li>\n\n\n\n<li><strong>Durabilit\u00e9<\/strong><br>En tant qu&rsquo;investisseur responsable, nous prenons \u00e9galement en compte les crit\u00e8res environnementaux, sociaux et de gouvernance (ESG) dans nos d\u00e9cisions d&rsquo;investissement.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jetez tout de suite un coup d&rsquo;\u0153il aux rapports d&rsquo;investissement trimestriels de notre contr\u00f4leur d&rsquo;investissement externe.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"gb-headline gb-headline-c148aae2 gb-headline-text\"><strong>Pool de placement Avanea 30<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le pool de placement, qui existe depuis sa cr\u00e9ation, dispose actuellement d&rsquo;une fortune d&rsquo;environ 230 millions de francs suisses. La strat\u00e9gie d&rsquo;e&rsquo;investissement du pool de placement Avanea 30 pr\u00e9voit une part d&rsquo;actions de 30% avec une fourchette de 10% \u00e0 50%. Depuis le 1.1.2024, la <a href=\"\">soci\u00e9t\u00e9 Dr. Pirmin Hotz Verm\u00f6gensverwaltungen AG<\/a> \u00e0 Baar est responsable de la gestion de fortune du pool Avanea 30.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"gb-container gb-container-b6c46c66\">\n<div class=\"gb-container gb-container-09b4f29d\">\n\n<h3 class=\"gb-headline gb-headline-c32336b7 gb-headline-text\">Allocation d&rsquo;actifs strat\u00e9gique Avanea 30<\/h3>\n\n\n<div class=\"gb-container gb-container-21cebed9\">\n<section id=\"digicube-block-66ab4b618dbee\"  class=\"DEMO\">\r\n    <div class=\"pie-wrapper\">\r\n        <div class=\"pie-left\">\r\n            <div class=\"chart\">\r\n                <canvas id=\"doughnutChart-block_bae3f5fd2ad10626c803425f0ef1abd6\" style=\"width:100%;max-width:700px\"><\/canvas>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"pie-right\">\r\n                        <div class=\"percentage-wrapper\" data-index=\"0\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">5%<\/span>\r\n                    <span class=\"title\">Liquidit\u00e9<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"1\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">30%<\/span>\r\n                    <span class=\"title\">Obligations CHF<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"2\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">15%<\/span>\r\n                    <span class=\"title\">Obligations FW<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"3\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">15%<\/span>\r\n                    <span class=\"title\">Actions Suisse<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"4\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">15%<\/span>\r\n                    <span class=\"title\">Actions \u00e9trang\u00e8res<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"5\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">15%<\/span>\r\n                    <span class=\"title\">Immobilier national<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"6\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">5%<\/span>\r\n                    <span class=\"title\">Placements alternatifs<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n<script>\r\ndocument.addEventListener('DOMContentLoaded', function() {\r\n    var blockId = \"doughnutChart-block_bae3f5fd2ad10626c803425f0ef1abd6\"; \/\/ Unique ID for the current block instance\r\n    var wrapper = document.getElementById(blockId).closest('.pie-wrapper'); \/\/ Scope to the correct pie-wrapper\r\n\r\n    var data = {\r\n        datasets: [{\r\n            data: [\r\n                                5,\r\n                                30,\r\n                                15,\r\n                                15,\r\n                                15,\r\n                                15,\r\n                                5,\r\n                            ],\r\n            borderColor: '#bd0118',\r\n            backgroundColor: '#fff',\r\n            borderWidth: 10,\r\n            pointRadius: 5,\r\n            pointHoverRadius: 8,\r\n            hoverBorderWidth: 2,\r\n            hoverBorderColor: '#fff',\r\n            hoverBackgroundColor:'#fff',\r\n        }]\r\n    };\r\n\r\n    var options = {\r\n        cutout: window.innerWidth < 991 ? 50 : 200,\r\n        responsive: true,\r\n        maintainAspectRatio: false,\r\n        plugins: {\r\n            tooltip: { enabled: false }\r\n        },\r\n        events: ['mousemove', 'mouseout', 'click', 'touchstart', 'touchmove'],\r\n        onHover: function (event, chartElement) {\r\n            if (chartElement.length > 0) {\r\n                var index = chartElement[0].element.$context.index;\r\n                wrapper.querySelectorAll('.percentage-wrapper').forEach(function (percentageWrapper) {\r\n                    percentageWrapper.classList.remove('hovered');\r\n                });\r\n                wrapper.querySelector('.percentage-wrapper[data-index=\"'+index+'\"]').classList.add('hovered');\r\n            } else {\r\n                wrapper.querySelectorAll('.percentage-wrapper').forEach(function (percentageWrapper) {\r\n                    percentageWrapper.classList.remove('hovered');\r\n                });\r\n            }\r\n        }\r\n    };\r\n\r\n    var ctx = document.getElementById(blockId).getContext('2d'); \/\/ Select the unique canvas\r\n    var myDoughnutChart = new Chart(ctx, {\r\n        type: 'doughnut',\r\n        data: data,\r\n        options: options\r\n    });\r\n\r\n    var percentageWrappers = wrapper.querySelectorAll('.percentage-wrapper[data-index]');\r\n    percentageWrappers.forEach(function(wrapper, key) {\r\n        wrapper.addEventListener('click', function() {\r\n            percentageWrappers.forEach(function(element) {\r\n                element.classList.remove('active');\r\n            });\r\n            wrapper.classList.add('active');\r\n            myDoughnutChart.setActiveElements([\r\n                {\r\n                    datasetIndex: 0,\r\n                    index: key,\r\n                }\r\n            ]);\r\n            myDoughnutChart.update();\r\n        });\r\n    });\r\n});\r\n<\/script>\r\n\n<\/div>\n<\/div>\n<\/div>\n\n\n<h3 class=\"gb-headline gb-headline-162b6d66 gb-headline-text\">Performance et rapports<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous publions des rapports trimestriels complets sur la performance de nos investissements.\nCes rapports vous donnent un aper\u00e7u d\u00e9taill\u00e9 de l&rsquo;\u00e9volution et de la composition de notre portefeuille. <\/p>\n\n\n<div class=\"gb-container gb-container-46386093 gb-accordion\">\n<div class=\"gb-container gb-container-aa7281e2 gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-4aa90e53 gb-accordion__toggle\" id=\"gb-accordion-toggle-4aa90e53\"><span class=\"gb-button-text\">Rapports trimestriels 2024<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 22.949 22.949\" height=\"22.949\" class=\"gb-accordion__icon\" width=\"22.949\">   <path transform=\"translate(-5.664 26.05)\" d=\"M28.613-12.939H18.75V-3.1H15.5v-9.839H5.664v-3.271H15.5V-26.05H18.75v9.839h9.863Z\" data-name=\"Path 66\" id=\"Path_66\"><\/path> <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 22.949 3.271\" height=\"3.271\" width=\"22.949\" class=\"gb-accordion__icon-open\">   <path transform=\"translate(-5.664 16.211)\" d=\"M28.613-12.939H5.664v-3.271H28.613Z\" data-name=\"Path 66\" id=\"Path_66\"><\/path> <\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-d91abceb\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-d91abceb\">\n<section id=\"digicube-block-6646177393526\"  class=\"downloads__block\">\r\n\r\n\r\n\r\n    <div class=\"downloads__container__each\">            <div class=\"downloads__container make__columns \">\r\n                                            <div class=\" 0 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2025\/01\/2024-Q4_Avanea_Bericht.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2024_Q4_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                                            <div class=\" 1 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/10\/2024-Q3_Avanea_Bericht.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2024_Q3_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                                            <div class=\" 2 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/08\/2024-Q2_Avanea_Bericht.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2024_Q2_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                                            <div class=\" 3 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/06\/2024-Q1_Avanea_Bericht-1.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2024_Q1_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                \r\n            <\/div>\r\n                <\/div>\r\n    \r\n<\/section>\n<\/div><\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-6f331c48 gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-f5a75ba3 gb-accordion__toggle\" id=\"gb-accordion-toggle-f5a75ba3\"><span class=\"gb-button-text\">Rapports trimestriels 2023<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 22.949 22.949\" height=\"22.949\" class=\"gb-accordion__icon\" width=\"22.949\">   <path transform=\"translate(-5.664 26.05)\" d=\"M28.613-12.939H18.75V-3.1H15.5v-9.839H5.664v-3.271H15.5V-26.05H18.75v9.839h9.863Z\" data-name=\"Path 66\" id=\"Path_66\"><\/path> <\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 22.949 3.271\" height=\"3.271\" width=\"22.949\" class=\"gb-accordion__icon-open\">   <path transform=\"translate(-5.664 16.211)\" d=\"M28.613-12.939H5.664v-3.271H28.613Z\" data-name=\"Path 66\" id=\"Path_66\"><\/path> <\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-d945c392\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-d945c392\">\n<section id=\"digicube-block-66461773935b0\"  class=\"downloads__block\">\r\n\r\n\r\n\r\n    <div class=\"downloads__container__each\">            <div class=\"downloads__container make__columns \">\r\n                                            <div class=\" 0 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/06\/2023-Q4_Avanea_Bericht.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2023_Q4_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                                            <div class=\" 1 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/06\/2023-Q3_Avanea_Bericht.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2023_Q3_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                                            <div class=\" 2 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/06\/2023-Q2_Avanea_Bericht.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2023_Q2_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                                            <div class=\" 3 downloads__item\">\r\n\r\n                                <a href=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/08\/2024-Q1_Avanea_Bericht.pdf\" target=\"_blank\">\r\n                                    <div class=\"downloads__item__content\">\r\n                                        <p> 2023_Q1_Anlagebericht<\/p>\r\n                                    <\/div>\r\n                                <\/a>\r\n                            <\/div>\r\n                \r\n            <\/div>\r\n                <\/div>\r\n    \r\n<\/section>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"gb-headline gb-headline-91a22cfb gb-headline-text\">Reporting ESG Avanea Pool 30<br><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour l&rsquo;\u00e9valuation ESG, nous nous appuyons d&rsquo;une part sur les donn\u00e9es des deux principales soci\u00e9t\u00e9s d&rsquo;analyse ESG, MSCI et S&amp;P Global.\nD&rsquo;autre part, une \u00e9valuation quantitative et\/ou qualitative (sur la base de rapports de durabilit\u00e9 et de rapports d&rsquo;activit\u00e9 sp\u00e9cifiques \u00e0 l&rsquo;entreprise) de Dr. Pirmin Hotz Verm\u00f6gensverwaltungen AG est int\u00e9gr\u00e9e \u00e0 l&rsquo;analyse, en particulier dans le domaine des titres \u00e0 revenu fixe et des entreprises \u00e0 petite et moyenne capitalisation.\nMSCI examine toutes les entreprises sur la base de 10 th\u00e8mes cl\u00e9s (4 dans le domaine de l&rsquo;environnement (E), 4 dans le domaine social (S) et 2 dans le domaine de la gouvernance (G)).\nL&rsquo;\u00e9valuation est effectu\u00e9e sur une base relative par rapport au secteur concern\u00e9.\nPour son \u00e9valuation, S&amp;P Global se r\u00e9f\u00e8re \u00e0 des r\u00e9ponses \u00e0 des questionnaires sp\u00e9cifiques au secteur et \u00e0 des donn\u00e9es d&rsquo;entreprises accessibles au public.\nEn outre, les m\u00e9dias sont constamment consult\u00e9s pour d\u00e9tecter d&rsquo;\u00e9ventuelles controverses, qui sont \u00e9galement prises en compte dans l&rsquo;\u00e9valuation.     <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>M\u00e9thodologie d&rsquo;\u00e9valuation<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque position du portefeuille est \u00e9valu\u00e9e selon des crit\u00e8res ESG (voir m\u00e9thodologie d&rsquo;\u00e9valuation).\nIl en r\u00e9sulte une valeur ESG sp\u00e9cifique \u00e0 l&rsquo;entreprise, comprise entre 0 et 100.\nSur la base de cette valeur, les entreprises sont ensuite class\u00e9es dans l&rsquo;une des cat\u00e9gories suivantes :  <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Cat\u00e9gorie Valeur<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-group is-layout-grid wp-container-core-group-is-layout-9d260ee2 wp-block-group-is-layout-grid\">\n<p class=\"wp-block-paragraph\"><strong>Top <\/strong>&gt;87.5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fort<\/strong> &gt;62.5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Moyen <\/strong>&gt;37.5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Faible<\/strong> &gt;12.5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Flop<\/strong> &lt;12.5<\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La valeur ESG de HotzVV r\u00e9sulte de la moyenne des valeurs individuelles.\nLa valeur s&rsquo;\u00e9l\u00e8ve au 30.06.2024 : <\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"713\" height=\"589\" src=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/07\/image-4.png\" alt=\"\" class=\"wp-image-1183\" srcset=\"https:\/\/avanea.ch\/wp-content\/uploads\/2024\/07\/image-4.png 713w, https:\/\/avanea.ch\/wp-content\/uploads\/2024\/07\/image-4-300x248.png 300w\" sizes=\"(max-width: 713px) 100vw, 713px\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"gb-headline gb-headline-1b9a3826 gb-headline-text\"><strong>Pool de placement PizSol InvestPool<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La pr\u00e9voyance professionnelle est \u00e0 bien des \u00e9gards l&rsquo;institution la plus importante pour les salari\u00e9s afin de se constituer un patrimoine pendant le processus de travail et de couvrir les risques de maladie et de d\u00e9c\u00e8s de mani\u00e8re professionnelle. En raison de l&rsquo;augmentation de l&rsquo;esp\u00e9rance de vie et de la dur\u00e9e des rentes, le financement et donc la performance des placements financiers jouent un r\u00f4le central. Un rendement durable associ\u00e9 \u00e0 une protection du capital int\u00e9gr\u00e9e sont les garants de notre concept de r\u00e9ussite et de la promesse de retraite faite \u00e0 vos collaborateurs. PizSol InvestPool est le r\u00e9sultat d&rsquo;une collaboration entre deux experts ind\u00e9pendants et combine les approches innovantes de Avanea Caisse de pension avec le savoir-faire en mati\u00e8re de pr\u00e9voyance professionnelle et l&rsquo;exp\u00e9rience de Wyss und Partner pour la gestion des placements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir du 01.01.2025, Avanea Caisse de pension s&rsquo;enrichit d&rsquo;un nouveau pool de placement. La strat\u00e9gie d&rsquo;investissement du pool de placement PizSol pr\u00e9voit une part d&rsquo;actions de 40% avec une fourchette de 30% \u00e0 50%. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une strat\u00e9gie d&rsquo;investissement ax\u00e9e sur le rendement ainsi qu&rsquo;une allocation dynamique des placements, c&rsquo;est-\u00e0-dire la r\u00e9action aux \u00e9v\u00e9nements du march\u00e9 et l&rsquo;exploitation des opportunit\u00e9s qui se pr\u00e9sentent, jouent un r\u00f4le central pour atteindre, voire d\u00e9passer, les r\u00e9sultats d&rsquo;investissement souhait\u00e9s.\nL&rsquo;objectif final est d&rsquo;obtenir une pension de retraite attrayante pour les assur\u00e9s.\nUn taux de conversion enveloppant \u00e9lev\u00e9, actuellement de 6,1%, fait partie de cette strat\u00e9gie.\nLes comp\u00e9tences de mise en \u0153uvre de <a href=\"\">Wyss &amp; Partner Verm\u00f6gensverwaltung und Anlageberatung AG<\/a> garantissent une mise en \u0153uvre avec une forte gouvernance tout en permettant la flexibilit\u00e9 et la rapidit\u00e9 n\u00e9cessaires pour saisir les opportunit\u00e9s du march\u00e9.   <\/p>\n\n\n<div class=\"gb-container gb-container-94c4a7c1\">\n<div class=\"gb-container gb-container-c8279579\">\n\n<h3 class=\"gb-headline gb-headline-ee8923f3 gb-headline-text\">Allocation d&rsquo;actifs strat\u00e9gique PizSol InvestPool<\/h3>\n\n\n<div class=\"gb-container gb-container-bec28c5e\">\n<section id=\"digicube-block-66ab4b618dbee\"  class=\"DEMO\">\r\n    <div class=\"pie-wrapper\">\r\n        <div class=\"pie-left\">\r\n            <div class=\"chart\">\r\n                <canvas id=\"doughnutChart-block_26c217580d1899c058086e824132ea6c\" style=\"width:100%;max-width:700px\"><\/canvas>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"pie-right\">\r\n                        <div class=\"percentage-wrapper\" data-index=\"0\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">5%<\/span>\r\n                    <span class=\"title\">Liquidit\u00e9<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"1\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">20%<\/span>\r\n                    <span class=\"title\">Obligations CHF<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"2\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">15%<\/span>\r\n                    <span class=\"title\">Obligations FW<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"3\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">20%<\/span>\r\n                    <span class=\"title\">Actions Suisse<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"4\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">20%<\/span>\r\n                    <span class=\"title\">Actions \u00e9trang\u00e8res<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"5\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">15%<\/span>\r\n                    <span class=\"title\">Immobilier national<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                        <div class=\"percentage-wrapper\" data-index=\"6\">\r\n                <div class=\"p-content\">\r\n                    <span class=\"number\">5%<\/span>\r\n                    <span class=\"title\">Placements alternatifs<\/span>\r\n                <\/div>\r\n            <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n<script>\r\ndocument.addEventListener('DOMContentLoaded', function() {\r\n    var blockId = \"doughnutChart-block_26c217580d1899c058086e824132ea6c\"; \/\/ Unique ID for the current block instance\r\n    var wrapper = document.getElementById(blockId).closest('.pie-wrapper'); \/\/ Scope to the correct pie-wrapper\r\n\r\n    var data = {\r\n        datasets: [{\r\n            data: [\r\n                                5,\r\n                                20,\r\n                                15,\r\n                                20,\r\n                                20,\r\n                                15,\r\n                                5,\r\n                            ],\r\n            borderColor: '#bd0118',\r\n            backgroundColor: '#fff',\r\n            borderWidth: 10,\r\n            pointRadius: 5,\r\n            pointHoverRadius: 8,\r\n            hoverBorderWidth: 2,\r\n            hoverBorderColor: '#fff',\r\n            hoverBackgroundColor:'#fff',\r\n        }]\r\n    };\r\n\r\n    var options = {\r\n        cutout: window.innerWidth < 991 ? 50 : 200,\r\n        responsive: true,\r\n        maintainAspectRatio: false,\r\n        plugins: {\r\n            tooltip: { enabled: false }\r\n        },\r\n        events: ['mousemove', 'mouseout', 'click', 'touchstart', 'touchmove'],\r\n        onHover: function (event, chartElement) {\r\n            if (chartElement.length > 0) {\r\n                var index = chartElement[0].element.$context.index;\r\n                wrapper.querySelectorAll('.percentage-wrapper').forEach(function (percentageWrapper) {\r\n                    percentageWrapper.classList.remove('hovered');\r\n                });\r\n                wrapper.querySelector('.percentage-wrapper[data-index=\"'+index+'\"]').classList.add('hovered');\r\n            } else {\r\n                wrapper.querySelectorAll('.percentage-wrapper').forEach(function (percentageWrapper) {\r\n                    percentageWrapper.classList.remove('hovered');\r\n                });\r\n            }\r\n        }\r\n    };\r\n\r\n    var ctx = document.getElementById(blockId).getContext('2d'); \/\/ Select the unique canvas\r\n    var myDoughnutChart = new Chart(ctx, {\r\n        type: 'doughnut',\r\n        data: data,\r\n        options: options\r\n    });\r\n\r\n    var percentageWrappers = wrapper.querySelectorAll('.percentage-wrapper[data-index]');\r\n    percentageWrappers.forEach(function(wrapper, key) {\r\n        wrapper.addEventListener('click', function() {\r\n            percentageWrappers.forEach(function(element) {\r\n                element.classList.remove('active');\r\n            });\r\n            wrapper.classList.add('active');\r\n            myDoughnutChart.setActiveElements([\r\n                {\r\n                    datasetIndex: 0,\r\n                    index: key,\r\n                }\r\n            ]);\r\n            myDoughnutChart.update();\r\n        });\r\n    });\r\n});\r\n<\/script>\r\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"gb-headline gb-headline-0018661b gb-headline-text\"><strong>Comportement de vote<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les institutions de pr\u00e9voyance doivent exercer les droits de vote dans l&rsquo;int\u00e9r\u00eat des assur\u00e9s dans les entreprises cot\u00e9es en bourse ayant leur si\u00e8ge en Suisse.\nDans le cas de la caisse de pension Avanea, cela est effectu\u00e9 par la gestion de fortune ou, dans des cas exceptionnels, par le g\u00e9rant.\nLes principes suivants s&rsquo;appliquent \u00e0 l&rsquo;exercice des droits de vote :  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;\u00e9lection des membres du conseil d&rsquo;administration, du comit\u00e9 de r\u00e9mun\u00e9ration, de l&rsquo;organe de r\u00e9vision et du repr\u00e9sentant ind\u00e9pendant doit avoir lieu chaque ann\u00e9e.<\/li>\n\n\n\n<li>Pas de double mandat Conseil d&rsquo;administration \/ Direction g\u00e9n\u00e9rale<\/li>\n\n\n\n<li>Le montant total des r\u00e9mun\u00e9rations vers\u00e9es au conseil d&rsquo;administration et \u00e0 la direction est fix\u00e9 chaque ann\u00e9e.<\/li>\n\n\n\n<li>Pas d&rsquo;indemnit\u00e9s de d\u00e9part ou de r\u00e9mun\u00e9rations convenues ou vers\u00e9es \u00e0 l&rsquo;avance<\/li>\n\n\n\n<li>Pas de commissions pour l&rsquo;acquisition ou le transfert d&rsquo;entreprises ou de parties d&rsquo;entreprises<\/li>\n\n\n\n<li>Pas de r\u00e9mun\u00e9ration li\u00e9e \u00e0 la performance non conforme aux statuts<\/li>\n\n\n\n<li>Possibilit\u00e9 de voter par voie \u00e9lectronique<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Si ces principes ne sont pas respect\u00e9s, la caisse de pension Avanea votera contre les propositions du conseil d&rsquo;administration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les personnes assur\u00e9es sont inform\u00e9es au moins une fois par an sous une forme appropri\u00e9e &#8211; dans le rapport annuel et\/ou via le site Internet &#8211; du comportement de vote.<\/p>\n\n\n<div class=\"gb-container gb-container-69aac571\">\n\n<h3 class=\"wp-block-heading\">Contact<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Des questions sur nos installations ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre \u00e9quipe d&rsquo;experts est \u00e0 votre disposition pour r\u00e9pondre \u00e0 vos questions sur nos strat\u00e9gies et d\u00e9cisions d&rsquo;investissement.\nN&rsquo;h\u00e9sitez pas \u00e0 nous contacter : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>T\u00e9l\u00e9phone<\/strong>: +41 44 680 24 24<\/li>\n\n\n\n<li><strong>Courrier \u00e9lectronique<\/strong>: <a>info@avanea.ch<\/a><\/li>\n\n\n\n<li><strong>Adresse<\/strong>: Avanea Pensionskasse, Merkurstrasse 3, CH-8820 W\u00e4denswil<\/li>\n<\/ul>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nous adoptons des strat\u00e9gies d&rsquo;investissement \u00e0 long terme afin de garantir la s\u00e9curit\u00e9 de votre \u00e9pargne retraite. Notre philosophie d&rsquo;investissement &#8230; <a title=\"Placements\" class=\"read-more\" href=\"https:\/\/avanea.ch\/fr\/placements\/\" aria-label=\"En savoir plus sur Placements\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":2065,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2103","page","type-page","status-publish","has-post-thumbnail"],"acf":[],"_links":{"self":[{"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/pages\/2103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/comments?post=2103"}],"version-history":[{"count":7,"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/pages\/2103\/revisions"}],"predecessor-version":[{"id":3568,"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/pages\/2103\/revisions\/3568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/media\/2065"}],"wp:attachment":[{"href":"https:\/\/avanea.ch\/fr\/wp-json\/wp\/v2\/media?parent=2103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}